{"id":7921,"date":"2025-12-05T14:19:31","date_gmt":"2025-12-05T19:19:31","guid":{"rendered":"https:\/\/www.uqac.ca\/calendrier\/?post_type=tribe_events&#038;p=7921"},"modified":"2025-12-05T14:23:10","modified_gmt":"2025-12-05T19:23:10","slug":"encadrer-lutilisation-de-lia-generative-iag-dans-les-travaux-etudiants-nouveaux-outils-et-bonnes-pratiques-3","status":"publish","type":"tribe_events","link":"https:\/\/www.uqac.ca\/calendrier\/evenement\/encadrer-lutilisation-de-lia-generative-iag-dans-les-travaux-etudiants-nouveaux-outils-et-bonnes-pratiques-3\/","title":{"rendered":"Encadrer l&rsquo;utilisation de l&rsquo;IA g\u00e9n\u00e9rative (IAg) dans les travaux \u00e9tudiants : nouveaux outils et bonnes pratiques"},"content":{"rendered":"<p>L\u2019IAg est d\u00e9sormais omnipr\u00e9sente dans le paysage de l\u2019enseignement sup\u00e9rieur. Pour soutenir une int\u00e9gration \u00e9thique, transparente et p\u00e9dagogique de ces outils, de nouveaux dispositifs ont \u00e9t\u00e9 int\u00e9gr\u00e9s au gabarit de plan de cours de l\u2019UQAC. Ceux-ci permettent aux personnes enseignantes d\u2019indiquer\u00a0 aux personnes \u00e9tudiantes, pour chaque travail \u00e0 remettre, le niveau d\u2019utilisation de l\u2019IAg autoris\u00e9. Des pictogrammes simples accompagnent cette d\u00e9marche afin de permettre aux personnes \u00e9tudiantes de d\u00e9clarer clairement le niveau d\u2019IAg utilis\u00e9 dans les \u00e9valuations. En compl\u00e9ment, un questionnaire facultatif est propos\u00e9 pour recueillir, de mani\u00e8re plus fine, les strat\u00e9gies d\u2019utilisation de l\u2019IAg par les personnes \u00e9tudiantes.<\/p>\n<p>Lors de cette rencontre, nous pr\u00e9senterons les nouveaut\u00e9s int\u00e9gr\u00e9es au gabarit de plan de cours ; les pictogrammes et leur signification; le questionnaire facultatif destin\u00e9 aux personnes \u00e9tudiantes; des exemples d\u2019application dans divers contextes p\u00e9dagogiques et des pistes pour susciter la r\u00e9flexion et encourager une utilisation responsable et p\u00e9dagogique de l\u2019IAg.<\/p>\n<p>Cette formation s\u2019adresse \u00e0 toutes les personnes enseignantes souhaitant baliser l\u2019usage de l\u2019IAg dans leurs cours.<\/p>\n<p><strong>Pour s&rsquo;inscrire \u00e0 la formation: <a href=\"https:\/\/salles.bibliotheque.uqac.ca\/event\/3971272\">https:\/\/salles.bibliotheque.uqac.ca\/event\/3971272<\/a><\/strong><\/p>\n<p><strong>Pour en savoir plus sur la Communaut\u00e9 de partage concernant l\u2019utilisation de l\u2019IA en enseignement de l&rsquo;UQAC (CoPIAe): <a href=\"https:\/\/www.uqac.ca\/ressourcespedago\/copiae\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.uqac.ca\/ressourcespedago\/copiae\/<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019IAg est d\u00e9sormais omnipr\u00e9sente dans le paysage de l\u2019enseignement sup\u00e9rieur. Pour soutenir une int\u00e9gration \u00e9thique, transparente et p\u00e9dagogique de ces outils, de nouveaux dispositifs ont \u00e9t\u00e9 int\u00e9gr\u00e9s au gabarit de [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[126],"class_list":["post-7921","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-formations","cat_formations"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/tribe_events\/7921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/users\/36"}],"version-history":[{"count":4,"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/tribe_events\/7921\/revisions"}],"predecessor-version":[{"id":7931,"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/tribe_events\/7921\/revisions\/7931"}],"wp:attachment":[{"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/media?parent=7921"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/tags?post=7921"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.uqac.ca\/calendrier\/wp-json\/wp\/v2\/tribe_events_cat?post=7921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}