﻿{"id":18930,"date":"2021-11-14T10:28:22","date_gmt":"2021-11-14T15:28:22","guid":{"rendered":"http:\/\/www.uqac.ca\/emploi\/?p=18930"},"modified":"2021-11-14T10:28:22","modified_gmt":"2021-11-14T15:28:22","slug":"a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees","status":"publish","type":"post","link":"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/","title":{"rendered":"A-216 &#8211; Responsable de laboratoires en sciences de la terre &#8211; Sciences appliqu\u00e9es"},"content":{"rendered":"<p>Le pr\u00e9sent avis a pour objet d&rsquo;informer les int\u00e9ress\u00e9s de la nomination de monsieur R\u00e9my Poulin au poste de Responsable de laboratoires en sciences de la terre au D\u00e9partement des sciences appliqu\u00e9es ,\u00a0et ce, \u00e0 compter du 2 ao\u00fbt 2021.<\/p>\n<p>.<br \/>\nNous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9.<\/p>\n<p><em><strong>Le Service des ressources humaines<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sent avis a pour objet d&rsquo;informer les int\u00e9ress\u00e9s de la nomination de monsieur R\u00e9my Poulin au poste de Responsable de laboratoires en sciences de la terre au D\u00e9partement des sciences appliqu\u00e9es ,\u00a0et ce, \u00e0 compter du 2 ao\u00fbt 2021. . Nous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9. Le Service des ressources humaines<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119],"tags":[],"class_list":["post-18930","post","type-post","status-publish","format-standard","hentry","category-avis-de-nomination"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>A-216 - Responsable de laboratoires en sciences de la terre - Sciences appliqu\u00e9es - emploi-uqac<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"A-216 - Responsable de laboratoires en sciences de la terre - Sciences appliqu\u00e9es - emploi-uqac\" \/>\r\n<meta property=\"og:description\" content=\"Le pr\u00e9sent avis a pour objet d&rsquo;informer les int\u00e9ress\u00e9s de la nomination de monsieur R\u00e9my Poulin au poste de Responsable de laboratoires en sciences de la terre au D\u00e9partement des sciences appliqu\u00e9es ,\u00a0et ce, \u00e0 compter du 2 ao\u00fbt 2021. . Nous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9. Le Service des ressources humaines\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/\" \/>\r\n<meta property=\"og:site_name\" content=\"emploi-uqac\" \/>\r\n<meta property=\"article:published_time\" content=\"2021-11-14T15:28:22+00:00\" \/>\r\n<meta name=\"author\" content=\"srh\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"srh\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/\",\"url\":\"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/\",\"name\":\"A-216 - Responsable de laboratoires en sciences de la terre - Sciences appliqu\u00e9es - emploi-uqac\",\"isPartOf\":{\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#website\"},\"datePublished\":\"2021-11-14T15:28:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.uqac.ca\/emploi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A-216 &#8211; Responsable de laboratoires en sciences de la terre &#8211; Sciences appliqu\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#website\",\"url\":\"https:\/\/www.uqac.ca\/emploi\/\",\"name\":\"emploi-uqac\",\"description\":\"Le seul endroit pour tous les emplois offerts \u00e0 l&#039;UQAC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uqac.ca\/emploi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21\",\"name\":\"srh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g\",\"caption\":\"srh\"},\"sameAs\":[\"http:\/\/www.uqac.ca\/direction_services\/srh\"],\"url\":\"https:\/\/www.uqac.ca\/emploi\/author\/srh\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A-216 - Responsable de laboratoires en sciences de la terre - Sciences appliqu\u00e9es - emploi-uqac","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/","og_locale":"fr_CA","og_type":"article","og_title":"A-216 - Responsable de laboratoires en sciences de la terre - Sciences appliqu\u00e9es - emploi-uqac","og_description":"Le pr\u00e9sent avis a pour objet d&rsquo;informer les int\u00e9ress\u00e9s de la nomination de monsieur R\u00e9my Poulin au poste de Responsable de laboratoires en sciences de la terre au D\u00e9partement des sciences appliqu\u00e9es ,\u00a0et ce, \u00e0 compter du 2 ao\u00fbt 2021. . Nous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9. Le Service des ressources humaines","og_url":"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/","og_site_name":"emploi-uqac","article_published_time":"2021-11-14T15:28:22+00:00","author":"srh","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"srh"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/","url":"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/","name":"A-216 - Responsable de laboratoires en sciences de la terre - Sciences appliqu\u00e9es - emploi-uqac","isPartOf":{"@id":"https:\/\/www.uqac.ca\/emploi\/#website"},"datePublished":"2021-11-14T15:28:22+00:00","author":{"@id":"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21"},"breadcrumb":{"@id":"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uqac.ca\/emploi\/2021\/11\/14\/a-216-responsable-de-laboratoires-en-sciences-de-la-terre-sciences-appliquees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.uqac.ca\/emploi\/"},{"@type":"ListItem","position":2,"name":"A-216 &#8211; Responsable de laboratoires en sciences de la terre &#8211; Sciences appliqu\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.uqac.ca\/emploi\/#website","url":"https:\/\/www.uqac.ca\/emploi\/","name":"emploi-uqac","description":"Le seul endroit pour tous les emplois offerts \u00e0 l&#039;UQAC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uqac.ca\/emploi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21","name":"srh","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g","caption":"srh"},"sameAs":["http:\/\/www.uqac.ca\/direction_services\/srh"],"url":"https:\/\/www.uqac.ca\/emploi\/author\/srh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts\/18930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/comments?post=18930"}],"version-history":[{"count":1,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts\/18930\/revisions"}],"predecessor-version":[{"id":18931,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts\/18930\/revisions\/18931"}],"wp:attachment":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/media?parent=18930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/categories?post=18930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/tags?post=18930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}