﻿{"id":28909,"date":"2026-05-06T16:04:36","date_gmt":"2026-05-06T20:04:36","guid":{"rendered":"https:\/\/www.uqac.ca\/emploi\/?p=28909"},"modified":"2026-05-06T16:05:19","modified_gmt":"2026-05-06T20:05:19","slug":"26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants","status":"publish","type":"post","link":"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/","title":{"rendered":"26039 &#8211; Commis aux services \u00e0 la vie \u00e9tudiante &#8211; Direction des services aux \u00e9tudiants"},"content":{"rendered":"<p>Le pr\u00e9sent avis a pour objet d\u2019informer les int\u00e9ress\u00e9(e)s de la nomination de Tania Desgagn\u00e9 \u00e0 l&rsquo;affectation temporaire de commis aux services \u00e0 la vie \u00e9tudiante \u00e0 la Direction des services aux \u00e9tudiants, et ce, \u00e0 compter du 11 mai 2026. Nous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9. La Direction des ressources humaines.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sent avis a pour objet d\u2019informer les int\u00e9ress\u00e9(e)s de la nomination de Tania Desgagn\u00e9 \u00e0 l&rsquo;affectation temporaire de commis aux services \u00e0 la vie \u00e9tudiante \u00e0 la Direction des services aux \u00e9tudiants, et ce, \u00e0 compter du 11 mai 2026. Nous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9. La Direction des ressources humaines.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119],"tags":[],"class_list":["post-28909","post","type-post","status-publish","format-standard","hentry","category-avis-de-nomination"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>26039 - Commis aux services \u00e0 la vie \u00e9tudiante - Direction des services aux \u00e9tudiants - emploi-uqac<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"26039 - Commis aux services \u00e0 la vie \u00e9tudiante - Direction des services aux \u00e9tudiants - emploi-uqac\" \/>\r\n<meta property=\"og:description\" content=\"Le pr\u00e9sent avis a pour objet d\u2019informer les int\u00e9ress\u00e9(e)s de la nomination de Tania Desgagn\u00e9 \u00e0 l&rsquo;affectation temporaire de commis aux services \u00e0 la vie \u00e9tudiante \u00e0 la Direction des services aux \u00e9tudiants, et ce, \u00e0 compter du 11 mai 2026. Nous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9. La Direction des ressources humaines.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/\" \/>\r\n<meta property=\"og:site_name\" content=\"emploi-uqac\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-05-06T20:04:36+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-05-06T20:05:19+00:00\" \/>\r\n<meta name=\"author\" content=\"srh\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"srh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/\",\"url\":\"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/\",\"name\":\"26039 - Commis aux services \u00e0 la vie \u00e9tudiante - Direction des services aux \u00e9tudiants - emploi-uqac\",\"isPartOf\":{\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#website\"},\"datePublished\":\"2026-05-06T20:04:36+00:00\",\"dateModified\":\"2026-05-06T20:05:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.uqac.ca\/emploi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"26039 &#8211; Commis aux services \u00e0 la vie \u00e9tudiante &#8211; Direction des services aux \u00e9tudiants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#website\",\"url\":\"https:\/\/www.uqac.ca\/emploi\/\",\"name\":\"emploi-uqac\",\"description\":\"Le seul endroit pour tous les emplois offerts \u00e0 l&#039;UQAC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uqac.ca\/emploi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21\",\"name\":\"srh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g\",\"caption\":\"srh\"},\"sameAs\":[\"http:\/\/www.uqac.ca\/direction_services\/srh\"],\"url\":\"https:\/\/www.uqac.ca\/emploi\/author\/srh\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"26039 - Commis aux services \u00e0 la vie \u00e9tudiante - Direction des services aux \u00e9tudiants - emploi-uqac","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/","og_locale":"fr_CA","og_type":"article","og_title":"26039 - Commis aux services \u00e0 la vie \u00e9tudiante - Direction des services aux \u00e9tudiants - emploi-uqac","og_description":"Le pr\u00e9sent avis a pour objet d\u2019informer les int\u00e9ress\u00e9(e)s de la nomination de Tania Desgagn\u00e9 \u00e0 l&rsquo;affectation temporaire de commis aux services \u00e0 la vie \u00e9tudiante \u00e0 la Direction des services aux \u00e9tudiants, et ce, \u00e0 compter du 11 mai 2026. Nous lui souhaitons tout le succ\u00e8s d\u00e9sir\u00e9. La Direction des ressources humaines.","og_url":"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/","og_site_name":"emploi-uqac","article_published_time":"2026-05-06T20:04:36+00:00","article_modified_time":"2026-05-06T20:05:19+00:00","author":"srh","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"srh","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/","url":"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/","name":"26039 - Commis aux services \u00e0 la vie \u00e9tudiante - Direction des services aux \u00e9tudiants - emploi-uqac","isPartOf":{"@id":"https:\/\/www.uqac.ca\/emploi\/#website"},"datePublished":"2026-05-06T20:04:36+00:00","dateModified":"2026-05-06T20:05:19+00:00","author":{"@id":"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21"},"breadcrumb":{"@id":"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uqac.ca\/emploi\/2026\/05\/06\/26039-commis-aux-services-a-la-vie-etudiante-direction-des-services-aux-etudiants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.uqac.ca\/emploi\/"},{"@type":"ListItem","position":2,"name":"26039 &#8211; Commis aux services \u00e0 la vie \u00e9tudiante &#8211; Direction des services aux \u00e9tudiants"}]},{"@type":"WebSite","@id":"https:\/\/www.uqac.ca\/emploi\/#website","url":"https:\/\/www.uqac.ca\/emploi\/","name":"emploi-uqac","description":"Le seul endroit pour tous les emplois offerts \u00e0 l&#039;UQAC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uqac.ca\/emploi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/5a9ce9e0f4df72c39408a9705ba2ea21","name":"srh","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/emploi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a3755077de05358e1bc9c35d66d34555301a41552f3f759a60a8ed6a1ba5f9a?s=96&d=mm&r=g","caption":"srh"},"sameAs":["http:\/\/www.uqac.ca\/direction_services\/srh"],"url":"https:\/\/www.uqac.ca\/emploi\/author\/srh\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts\/28909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/comments?post=28909"}],"version-history":[{"count":2,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts\/28909\/revisions"}],"predecessor-version":[{"id":28911,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/posts\/28909\/revisions\/28911"}],"wp:attachment":[{"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/media?parent=28909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/categories?post=28909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uqac.ca\/emploi\/wp-json\/wp\/v2\/tags?post=28909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}