﻿{"id":1653,"date":"2011-04-26T14:41:00","date_gmt":"2011-04-26T14:41:00","guid":{"rendered":""},"modified":"2011-04-26T18:41:19","modified_gmt":"2011-04-26T18:41:19","slug":"Initiation-a-Sozi","status":"publish","type":"post","link":"https:\/\/www.uqac.ca\/pedagotic\/Initiation-a-Sozi\/","title":{"rendered":"Initiation \u00e0 Sozi"},"content":{"rendered":"<p>Voici, tr\u00e8s rapidement, tout ce que je vais tenter de dire et faire dans mon atelier avec les doigts sur les touches. \u00c7a semble possible, mais il ne faudra pas trainer!<\/p>\n<p><\/p>\n<h3>1. Dessin matriciel vs vectoriel<\/h3>\n<p><\/p>\n<p>Une matrice de point pour le premier. L&rsquo;encodage d&rsquo;une description de l&rsquo;image pour l&rsquo;autre.<\/p>\n<p><\/p>\n<h3>2. Pr\u00e9sentation de <a href=\"http:\/\/inkscape.org\/?lang=fr\" hreflang=\"fr\">Inkscape<\/a><\/h3>\n<p><\/p>\n<p>C&rsquo;est un logiciel libre auquel on peut ajouter des extensions. Il est relativement simple et plus que suffisamment puissant pour la majorit\u00e9 de vos besoins.<\/p>\n<p><\/p>\n<h3>3. Pr\u00e9sentation de Sozi<\/h3>\n<p><\/p>\n<p>C&rsquo;est un logiciel libre qui s&rsquo;ajoute \u00e0 Inkscape comme une extension. Sozi permet de cr\u00e9er facilement une s\u00e9rie de vues avec des transitions anim\u00e9es (zoom, d\u00e9placement) automatiquement.<\/p>\n<p><\/p>\n<p>Ex.: <a href=\"http:\/\/pedagotic.ca\/?post\/2011\/04\/22\/Les-logiciels-libres-et-Sozi\" hreflang=\"fr\">Ma pr\u00e9sentation sur les logiciels libres<\/a><\/p>\n<p><\/p>\n<h3>4. Prise en main d&rsquo;Inkscape<\/h3>\n<p><\/p>\n<p>Je vais pr\u00e9senter les fonctions de base, mais je recommande ce <a href=\"http:\/\/inkscape.org\/doc\/basic\/tutorial-basic.fr.html\" hreflang=\"fr\">tutoriel<\/a> disponible (avec plusieurs autres!) depuis le site d&rsquo;<a href=\"http:\/\/inkscape.org\/doc\/index.php?lang=fr\" hreflang=\"fr\">Inkscape<\/a>. Lorsque vous serez seul devant l&rsquo;ordinateur, il vous guidera pas \u00e0 pas.<\/p>\n<p><\/p>\n<p>Voici les fonctions de base que je vais certainement pr\u00e9senter:<\/p>\n<ul><\/p>\n<li>Comment modifier la taille et l&rsquo;orientation du canevas<\/li>\n<p><\/p>\n<li>Comment zoomer et se d\u00e9placer dans le canevas<\/li>\n<p><\/p>\n<li>Je vais expliquer le principe des calques<\/li>\n<p><\/p>\n<li>Comment cr\u00e9er une forme, ajuster sa taille et modifier ses caract\u00e9ristiques (Maj+CTRL+F)<\/li>\n<p><\/p>\n<li>Comment ins\u00e9rer du texte et modifier ses caract\u00e9ristiques<\/li>\n<p><\/p>\n<li>Importer une image matricielle ou vectorielle<\/li>\n<p><\/ul>\n<p>Ses fonctions devraient permettre de cr\u00e9er une premi\u00e8re pr\u00e9sentation Sozi.<\/p>\n<p><\/p>\n<p>Si d&rsquo;autres fonctions sont n\u00e9cessaires ou utiles, j&rsquo;improviserai en fonction des questions des participants.<\/p>\n<p><\/p>\n<h3>5. Cr\u00e9er un premier dessin \u00e0 animer.<\/h3>\n<p><\/p>\n<p>On va cr\u00e9er une petite pr\u00e9sentation personnelle qui comptera (au plus) 4 vues:<\/p>\n<ul><\/p>\n<li>notre nom (outil texte),<\/li>\n<p><\/p>\n<li>notre exp\u00e9rience d&rsquo;enseignement (une image import\u00e9e),<\/li>\n<p><\/p>\n<li>notre animal pr\u00e9f\u00e9r\u00e9 (une image import\u00e9e),<\/li>\n<p><\/p>\n<li>1 chose que l&rsquo;on aime par-dessus tout (une image import\u00e9e).<\/li>\n<p><\/ul>\n<p>Rassurez-vous, je ne demanderai pas aux participants de se pr\u00e9senter&#8230;<\/p>\n<p><\/p>\n<p>Pour gagner du temps, j&rsquo;ai d\u00e9j\u00e0 <a href=\"\/pgiroux\/public\/Images_UQO.zip\">regroup\u00e9 quelques images<\/a> que l&rsquo;on peut utiliser sans probl\u00e8me. Elles proviennent toutes du site <a href=\"http:\/\/www.openclipart.org' hreflang=\"fr\">OPEN CLIPART<\/a>.<\/p>\n<ul><\/p>\n<li>5.1 T\u00e9l\u00e9charger les images et d\u00e9compresser le dossier sur le bureau.<\/li>\n<p><\/ul>\n<p><\/p>\n<ul><\/p>\n<li>5.2 Calque 1: Utiliser l&rsquo;outil TEXTE pour \u00e9crire votre nom au centre du Canevas.<\/li>\n<p><\/ul>\n<p><\/p>\n<ul><\/p>\n<li>5.3 Calque 2: Du cot\u00e9 gauche, nous allons ensuite ins\u00e9rer une image repr\u00e9sentant un enseignant.<\/li>\n<p><\/ul>\n<h5>Conseils: Int\u00e9grer les images au fichier Inkscape est souvent plus avantageux que de les lier. Le fichier sera plus lourd, mais vous n&rsquo;aurez pas \u00e0 vous soucier de transporter les images en conservant intacts les liens les unissant. Par contre, un fichier trop lourd peut \u00eatre difficile \u00e0 g\u00e9rer sur certains ordinateurs&#8230;<\/h5>\n<ul><\/p>\n<li>5.4 Calque 3: En haut de votre nom, vous allez choisir une image d&rsquo;animal. \u00cates-vous du type chien, chat, poisson ou reptile?<\/li>\n<p><\/ul>\n<p><\/p>\n<ul><\/p>\n<li>5.5 Calque 4: \u00c0 droite de votre nom, vous allez ins\u00e9rer l&rsquo;image d&rsquo;un coeur qui repr\u00e9sentera une chose que vous aimez plus que tout.<\/li>\n<p><\/ul>\n<h3>6. Il faut maintenant animer le tout.<\/h3>\n<p><\/p>\n<p>\u00c9videmment, nous aurions pu jouer un peu plus avec l&rsquo;image. Par exemple, nous aurions pu cacher les images dans les lettres en les rapetissant. Nous aurions pu modifier les couleurs et les tailles, mais je ne crois pas que nous avions le temps&#8230;<\/p>\n<p><\/p>\n<h5>Conseil: Ne placez pas les \u00e9l\u00e9ments de deux vues subs\u00e9quentes trop loin les uns des autres. Lors de la transition, cela pourrait cr\u00e9er une trop grande impression de vitesse ou des changements de direction trop brusques lors de la transition.  J&rsquo;ai remarqu\u00e9 que \u00e7a donne la naus\u00e9e \u00e0 certains!<\/h5>\n<ul><\/p>\n<li>6.1 Le principe de Sozi est simple, il faut d&rsquo;abord d\u00e9finir les vues (zone et orientation) en utilisant des formes (cercles ou rectangles).<\/li>\n<p><\/ul>\n<p>Cr\u00e9er d&rsquo;abord un calque pour les animations. Faisons ensuite un rectangle autour de votre nom. Ce sera la vue initiale.<\/p>\n<p><\/p>\n<p>Faites la m\u00eame chose avec chacune des 3 images en prenant soin que le rectangle soit orient\u00e9 exactement comme l&rsquo;image (le bas du rectangle vers le bas de l&rsquo;image).<\/p>\n<p><\/p>\n<h5>Conseil: Ne serr\u00e9 pas trop la forme sur l&rsquo;image lorsque vous d\u00e9terminez une vue. Mieux vaut d\u00e9border, lors de la transition, les d\u00e9tails visuels ext\u00e9rieurs \u00e0 la vue seront autant de rep\u00e8res pour situer les gens et cr\u00e9er l&rsquo;impression de d\u00e9placement.<\/h5>\n<ul><\/p>\n<li>6.2 Il faut ensuite animer animer le tout. S\u00e9lectionner le rectangle d\u00e9limitant la premi\u00e8re vue, d\u00e9rouler le menu extension et cliquer sur SOZI<\/li>\n<p><\/ul>\n<p>Donner un nom \u00e0 cette vue, cliquer pour rendre le rectangle invisible, s\u00e9lectionner le type d&rsquo;animation et enregistrer. Votre vue devrait apparaitre dans la portion droite du panneau de contr\u00f4le de Sozi. Fermer ensuite le panneau de contr\u00f4le de Sozi et recommencer pour chaque vue. (Vous devrez peut-\u00eatre attendre une seconde ou deux.) N&rsquo;oubliez pas d&rsquo;enregistrer votre fichier!<\/p>\n<p><\/p>\n<h3>En terminant<\/h3>\n<p><\/p>\n<p>Personnellement, j&rsquo;aime bien utilis\u00e9 Sozi avec des cartes conceptuelles ou des longues listes ou une s\u00e9rie d&rsquo;\u00e9tapes. \u00c7a permet de centrer l&rsquo;attention des apprenants. Utilisez-le aussi lorsque vous pr\u00e9sentez des graphiques ou des sch\u00e9mas.<\/p>\n<p><\/p>\n<p>La majorit\u00e9 des logiciels soutenant la conception de cartes conceptuelles,de diagrammes, de graphiques ou de sch\u00e9mas permettent d&rsquo;exporter le r\u00e9sultat final en image JPEG, GIF ou PNG. Ce ne sont pas des formats vectoriels, mais il est tout de m\u00eame possible de les importer dans Inkscape et de les animer.<\/p>\n<p><\/p>\n<p>\u00c9vitez le texte, soyez visuel&#8230;  Lorsqu&rsquo;il y a du texte \u00e0 l&rsquo;\u00e9cran, les gens lisent avant de vous \u00e9couter. Une image vaut souvent mille mots. C&rsquo;est donc souvent moins gourmand en terme d&rsquo;espace et d&rsquo;animations.<\/p>\n<p><\/p>\n<p><a href=\"http:\/\/prezi.com\/a5ia1sbq2m6w\/les-medias-et-la-jeunesse' hreflang=\"fr\">Voici un dernier bon exemple.<\/a> Il n&rsquo;est pas parfait, mais j&rsquo;aime bien l&rsquo;utiliser avec mes \u00e9tudiants. Outre qu&rsquo;il a \u00e9t\u00e9 con\u00e7u avec Prezi, la m\u00e9taphore visuelle (chambre d&rsquo;un adolescent) est int\u00e9ressante et soutien la pr\u00e9sentation de la totalit\u00e9 d&rsquo;une enqu\u00eate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je l&rsquo;ai dit <a href=\"http:\/\/pedagotic.ca\/?post\/2011\/04\/22\/Les-logiciels-libres-et-Sozi\" hreflang=\"fr\">plus t\u00f4t cette semaine<\/a>, je vais \u00e0 Gatineau aujourd&rsquo;hui et demain.  En plus d&rsquo;une pr\u00e9sentation sur les logiciels libres, je parlerai de Sozi. Voici mon plan pour l&rsquo;atelier \u00ab\u00a0doigts sur les touches\u00a0\u00bb \u00e0 propos de Sozi.<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-1653","post","type-post","status-publish","format-standard","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/posts\/1653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/comments?post=1653"}],"version-history":[{"count":0,"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/posts\/1653\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/media?parent=1653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/categories?post=1653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uqac.ca\/pedagotic\/wp-json\/wp\/v2\/tags?post=1653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}