{"id":25006,"date":"2001-04-04T09:47:08","date_gmt":"2001-04-04T13:47:08","guid":{"rendered":"http:\/\/uqactualite.odev.ca\/?p=25006"},"modified":"2001-04-04T09:47:08","modified_gmt":"2001-04-04T13:47:08","slug":"luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001","status":"publish","type":"post","link":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/","title":{"rendered":"L&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d&rsquo;excellence pour l&rsquo;ann\u00e9e 2000-2001"},"content":{"rendered":"<p style=\"text-align: right\"><b>Embargo, le mercredi 4 avril 2001, 20 h<\/b><\/p>\n<p style=\"text-align: justify\">Chicoutimi, le 4 avril 2001<b> &#8212;<\/b> L&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi a proc\u00e9d\u00e9 aujourd&rsquo;hui \u00e0 la trenti\u00e8me remise annuelle des bourses et des prix d&rsquo;excellence. Au total, nos \u00e9tudiants se sont m\u00e9rit\u00e9 pr\u00e8s de 700 000 $. Le tout s&rsquo;est d\u00e9roul\u00e9 devant plus de cinq cents (500) personnes, au centre social de l&rsquo;Universit\u00e9.<\/p>\n<p style=\"text-align: justify\">Cette c\u00e9r\u00e9monie, l&rsquo;une des plus prestigieuses de l&rsquo;universit\u00e9 r\u00e9gionale, mettait en valeur le travail acad\u00e9mique et l&rsquo;accomplissement personnel de plus de deux cents (200) \u00e9tudiant(e)s des premier, deuxi\u00e8me et troisi\u00e8me cycles universitaires. Par la m\u00eame occasion, elle rendait hommage aux nombreux donateurs priv\u00e9s d&rsquo;ici et d&rsquo;ailleurs qui, de fa\u00e7on habituelle et r\u00e9guli\u00e8re, contribuent au support financier des \u00e9tudiants de l&rsquo;UQAC. Enfin, cette soir\u00e9e a d\u00e9montr\u00e9 une fois de plus l&rsquo;importance et la vitalit\u00e9 du programme des bourses d&rsquo;excellence qui, gr\u00e2ce \u00e0 la solidarit\u00e9 de ses partenaires, assure aux \u00e9tudiants un service des plus ad\u00e9quats et une aide financi\u00e8re tr\u00e8s appr\u00e9ci\u00e9e.<\/p>\n<p style=\"text-align: justify\">Cette ann\u00e9e, les bourses de premier cycle sont au nombre de cent vingt-sept (127) pour un montant de plus de 165 000 $. Les donateurs priv\u00e9s de la r\u00e9gion contribuent pour pr\u00e8s de cinquante (50) bourses d&rsquo;\u00e9tudes. Dix (10) bourses de la Fondation Desjardins, seize (16) bourses de la Fondation Gaston-L. Tremblay, onze (11) bourses de recherche d&rsquo;\u00e9t\u00e9 du Conseil de recherches en sciences naturelles et en g\u00e9nie du Canada (CRSNG), la m\u00e9daille Strathcona, le Prix universitaire d&rsquo;excellence de l&rsquo;Ordre des ing\u00e9nieurs, la bourse de la FSSA, la Fondation Place du Royaume, le Prix du Lieutenant-Gouverneur du Qu\u00e9bec, l&rsquo;Ordre des infirmier(\u00e8re)s et l&rsquo;Ordre des administrateurs agr\u00e9\u00e9s compl\u00e8tent l&rsquo;ensemble des bourses de premier cycle.<\/p>\n<p style=\"text-align: justify\">Aux deuxi\u00e8me et troisi\u00e8me cycles, soixante-seize (76) bourses d&rsquo;excellence totalisant pr\u00e8s de 495 000 $ ont \u00e9t\u00e9 remises au cours de la c\u00e9r\u00e9monie. Comme par le pass\u00e9, nos \u00e9tudiants ont pu compter sur l&rsquo;appui de nombreux donateurs priv\u00e9s tels: la Fondation Gaston-L. Tremblay, l&rsquo;Alcan, la Fondation Thomas-L\u00e9on-Tremblay, la Fondation Asselin, le programme de donateurs de deuxi\u00e8me cycle en sciences comptables, la Fondation de l&rsquo;UQAC, Celanese Canada. Plusieurs bourses ont \u00e9galement \u00e9t\u00e9 offertes gr\u00e2ce \u00e0 la participation institutionnelle de d\u00e9partements, modules, associations et organismes de l&rsquo;Universit\u00e9.<\/p>\n<p style=\"text-align: justify\">Aussi, les contributions financi\u00e8res du Conseil de recherches en sciences naturelles et en g\u00e9nie du Canada (CRSNG), du Conseil de recherche en Sciences humaines (CRSH), du Fonds pour la formation des chercheurs et l&rsquo;aide \u00e0 la recherche (Fonds FCAR) et du Programme d&rsquo;aide institutionnelle \u00e0 la recherche (PAIR) repr\u00e9sentent une part importante des sommes obtenues par les \u00e9tudiants aux cycles d&rsquo;\u00e9tudes sup\u00e9rieures.<\/p>\n<p style=\"text-align: justify\">Bourses du Fonds de d\u00e9veloppement de l&rsquo;UQAC &#8211; Lanc\u00e9e il y a bient\u00f4t 3 ans, la premi\u00e8re campagne de financement de l&rsquo;UQAC a permis jusqu&rsquo;\u00e0 maintenant d&rsquo;amasser pr\u00e8s de 8,4 millions de dollars en dons et engagements aupr\u00e8s des \u00e9tudiants, employ\u00e9s, retrait\u00e9s, dipl\u00f4m\u00e9s et donateurs du milieu socio-\u00e9conomique r\u00e9gional et national. L&rsquo;\u00e9quipe de b\u00e9n\u00e9vole dirig\u00e9e par notre pr\u00e9sident Monsieur Carroll L&rsquo;Italien, vice-pr\u00e9sident principal chez Bombardier et notre recteur Monsieur Bernard Angers, a donc d\u00e9pass\u00e9 ses objectifs et ce, au b\u00e9n\u00e9fice de nos \u00e9tudiants.<\/p>\n<p style=\"text-align: justify\">Cette ann\u00e9e, plus de 100 000 $ seront distribu\u00e9s dont tout pr\u00e8s de 35 000 $ nous viennent de donateurs qui ont demand\u00e9 \u00e0 l&rsquo;UQAC de cr\u00e9er des fonds de bourses permanents. Parmi ceux-ci, on retrouve Donohue\/Abitibi-Consolidated, Produits forestiers Alliance, Desjardins, T\u00e9l\u00e9syst\u00e8me, la Banque Royale, L&rsquo;Industrielle-Alliance et les Augustines de la Mis\u00e9ricorde de J\u00e9sus de Chicoutimi. D&rsquo;autres bourses nous viennent \u00e9galement de donateurs du milieu socio-\u00e9conomique et de donateurs de la communaut\u00e9 universitaire. D\u00e8s l&rsquo;an prochain, Amisk, Cain Lamarre Casgrain Wells et Le Groupe Jean Coutu se joindront \u00e0 ces donateurs pour encore augmenter le nombre de bourses offertes \u00e0 l&rsquo;UQAC. En plus de ces fonds de bourses, la Campagne a \u00e9galement permis d&rsquo;obtenir le soutien annuel de E.J. Turcotte inc. et R\u00e9cup\u00e8re Sol inc. Gr\u00e2ce \u00e0 ces donateurs, 42 100 $ r\u00e9parti en 28 bourses sont offertes \u00e0 l&rsquo;ensemble de nos \u00e9tudiants cette ann\u00e9e.<\/p>\n<p style=\"text-align: justify\">La direction et le personnel de l&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi f\u00e9licitent tous les boursiers et toutes les boursi\u00e8res 2000-2001. L&rsquo;Universit\u00e9 remercie \u00e9galement tous les donateurs de bourses d&rsquo;excellence qui contribuent largement au d\u00e9veloppement de notre universit\u00e9 r\u00e9gionale en soulignant le travail de nos meilleur(e)s \u00e9tudiant(e)s.<\/p>\n<p>&#8211; 30 &#8211;<\/p>\n<p style=\"text-align: justify\">Source:<\/p>\n<p style=\"text-align: justify\"><a href=\"mailto:dclaveau@uqac.uquebec.ca%20\">Denis Claveau<\/a>, agent d&rsquo;information<br \/>\nt\u00e9l\u00e9phone: (418) 545-5011, poste 2350<br \/>\nt\u00e9l\u00e9copieur : (418) 545-5012<br \/>\ndclaveau@uqac.uquebec.ca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embargo, le mercredi 4 avril 2001, 20 h Chicoutimi, le 4 avril 2001 &#8212; L&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi a proc\u00e9d\u00e9 aujourd&rsquo;hui \u00e0 la trenti\u00e8me remise annuelle des bourses et des prix d&rsquo;excellence. Au total, nos \u00e9tudiants se sont m\u00e9rit\u00e9 pr\u00e8s de 700 000 $. Le tout s&rsquo;est d\u00e9roul\u00e9 devant plus de cinq cents (500) [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":24879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2772],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>L&#039;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d&#039;excellence pour l&#039;ann\u00e9e 2000-2001 - UQACtualit\u00e9s<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"L&#039;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d&#039;excellence pour l&#039;ann\u00e9e 2000-2001 - UQACtualit\u00e9s\" \/>\r\n<meta property=\"og:description\" content=\"Embargo, le mercredi 4 avril 2001, 20 h Chicoutimi, le 4 avril 2001 &#8212; L&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi a proc\u00e9d\u00e9 aujourd&rsquo;hui \u00e0 la trenti\u00e8me remise annuelle des bourses et des prix d&rsquo;excellence. Au total, nos \u00e9tudiants se sont m\u00e9rit\u00e9 pr\u00e8s de 700 000 $. Le tout s&rsquo;est d\u00e9roul\u00e9 devant plus de cinq cents (500) [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/\" \/>\r\n<meta property=\"og:site_name\" content=\"UQACtualit\u00e9s\" \/>\r\n<meta property=\"article:published_time\" content=\"2001-04-04T13:47:08+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"620\" \/>\r\n\t<meta property=\"og:image:height\" content=\"301\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Service des communications et des relations publiques\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service des communications et des relations publiques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/\",\"name\":\"L'Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d'excellence pour l'ann\u00e9e 2000-2001 - UQACtualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg\",\"datePublished\":\"2001-04-04T13:47:08+00:00\",\"dateModified\":\"2001-04-04T13:47:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#primaryimage\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg\",\"contentUrl\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg\",\"width\":620,\"height\":301},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uqac.ca\/uqactualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d&rsquo;excellence pour l&rsquo;ann\u00e9e 2000-2001\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#website\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/\",\"name\":\"UQACtualit\u00e9s\",\"description\":\"Le portail des nouvelles de l&#039;UQAC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uqac.ca\/uqactualites\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018\",\"name\":\"Service des communications et des relations publiques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g\",\"caption\":\"Service des communications et des relations publiques\"},\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/author\/bap\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d'excellence pour l'ann\u00e9e 2000-2001 - UQACtualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/","og_locale":"fr_CA","og_type":"article","og_title":"L'Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d'excellence pour l'ann\u00e9e 2000-2001 - UQACtualit\u00e9s","og_description":"Embargo, le mercredi 4 avril 2001, 20 h Chicoutimi, le 4 avril 2001 &#8212; L&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi a proc\u00e9d\u00e9 aujourd&rsquo;hui \u00e0 la trenti\u00e8me remise annuelle des bourses et des prix d&rsquo;excellence. Au total, nos \u00e9tudiants se sont m\u00e9rit\u00e9 pr\u00e8s de 700 000 $. Le tout s&rsquo;est d\u00e9roul\u00e9 devant plus de cinq cents (500) [&hellip;]","og_url":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/","og_site_name":"UQACtualit\u00e9s","article_published_time":"2001-04-04T13:47:08+00:00","og_image":[{"width":620,"height":301,"url":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg","type":"image\/jpeg"}],"author":"Service des communications et des relations publiques","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service des communications et des relations publiques","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/","url":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/","name":"L'Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d'excellence pour l'ann\u00e9e 2000-2001 - UQACtualit\u00e9s","isPartOf":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#primaryimage"},"image":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg","datePublished":"2001-04-04T13:47:08+00:00","dateModified":"2001-04-04T13:47:08+00:00","author":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018"},"breadcrumb":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#primaryimage","url":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg","contentUrl":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2013\/07\/GRAF-Uqactualit\u00e9s-\u00c913-11.jpg","width":620,"height":301},{"@type":"BreadcrumbList","@id":"https:\/\/www.uqac.ca\/uqactualites\/2001\/04\/04\/luniversite-du-quebec-a-chicoutimi-souligne-ses-boursiers-et-boursieres-dexcellence-pour-lannee-2000-2001\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uqac.ca\/uqactualites\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi souligne ses boursiers et boursi\u00e8res d&rsquo;excellence pour l&rsquo;ann\u00e9e 2000-2001"}]},{"@type":"WebSite","@id":"https:\/\/www.uqac.ca\/uqactualites\/#website","url":"https:\/\/www.uqac.ca\/uqactualites\/","name":"UQACtualit\u00e9s","description":"Le portail des nouvelles de l&#039;UQAC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uqac.ca\/uqactualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018","name":"Service des communications et des relations publiques","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g","caption":"Service des communications et des relations publiques"},"url":"https:\/\/www.uqac.ca\/uqactualites\/author\/bap\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts\/25006"}],"collection":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/comments?post=25006"}],"version-history":[{"count":0,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts\/25006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/media\/24879"}],"wp:attachment":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/media?parent=25006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/categories?post=25006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/tags?post=25006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}