{"id":28979,"date":"2014-12-12T10:27:15","date_gmt":"2014-12-12T15:27:15","guid":{"rendered":"http:\/\/uqactualite.odev.ca\/?p=28979"},"modified":"2014-12-12T10:27:15","modified_gmt":"2014-12-12T15:27:15","slug":"soutenance-de-these-de-serge-lavoie","status":"publish","type":"post","link":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/","title":{"rendered":"Soutenance de th\u00e8se de Serge Lavoie"},"content":{"rendered":"<p style=\"text-align: justify\">\u00c9tienne H\u00e9bert, doyen des \u00e9tudes de l\u2019UQAC, invite la communaut\u00e9 universitaire \u00e0 assister \u00e0 la soutenance de th\u00e8se de Serge Lavoie, \u00e9tudiant au doctorat en sciences de l\u2019environnement\u00a0:<\/p>\n<p style=\"text-align: center\"><em>Isolement et caract\u00e9risation des principes actifs d\u2019abies balsamea et de cornus canadensis<\/em><em><br \/>\n<\/em><strong>Vendredi 19 d\u00e9cembre 2014\u00a0 <\/strong><strong>\u25aa<\/strong><strong>\u00a0 9\u00a0h<br \/>\nLocal P1-4280<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Direction de recherche<br \/>\n<\/strong>Andr\u00e9 Pichette (UQAC)<\/p>\n<p style=\"text-align: justify\"><strong>Codirection de recherche<br \/>\n<\/strong>Jean Legault (UQAC)<\/p>\n<p style=\"text-align: justify\"><strong>Jury d\u2019\u00e9valuation<br \/>\n<\/strong>Jacqueline Abaul (UFR SEN)<br \/>\nKarine Auclair (Universit\u00e9 McGill)<\/p>\n<p style=\"text-align: justify\"><strong>Pr\u00e9sidence du jury<br \/>\n<\/strong>Catherine Laprise (UQAC)<\/p>\n<p style=\"text-align: justify\">\nBienvenue \u00e0 toutes et \u00e0 tous!<\/p>\n<p style=\"text-align: justify\"><strong><br \/>\nRenseignements\u00a0:<\/strong><strong><br \/>\n<\/strong>Isabelle Savard, secr\u00e9taire (m\u00e9moires et th\u00e8ses)<br \/>\nD\u00e9canat des \u00e9tudes<br \/>\nUniversit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi<br \/>\n418 545-5011, poste\u00a04753\u00a0 \u25aa\u00a0 <span style=\"text-decoration: underline\"><a href=\"mailto:de_memoires_theses@uqac.ca\">de_memoires_theses@uqac.ca<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9tienne H\u00e9bert, doyen des \u00e9tudes de l\u2019UQAC, invite la communaut\u00e9 universitaire \u00e0 assister \u00e0 la soutenance de th\u00e8se de Serge Lavoie, \u00e9tudiant au doctorat en sciences de l\u2019environnement\u00a0: Isolement et caract\u00e9risation des principes actifs d\u2019abies balsamea et de cornus canadensis Vendredi 19 d\u00e9cembre 2014\u00a0 \u25aa\u00a0 9\u00a0h Local P1-4280 Direction de recherche Andr\u00e9 Pichette (UQAC) Codirection [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":20989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2772],"tags":[292,3,1441,1774,293,294],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Soutenance de th\u00e8se de Serge Lavoie - UQACtualit\u00e9s<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Soutenance de th\u00e8se de Serge Lavoie - UQACtualit\u00e9s\" \/>\r\n<meta property=\"og:description\" content=\"\u00c9tienne H\u00e9bert, doyen des \u00e9tudes de l\u2019UQAC, invite la communaut\u00e9 universitaire \u00e0 assister \u00e0 la soutenance de th\u00e8se de Serge Lavoie, \u00e9tudiant au doctorat en sciences de l\u2019environnement\u00a0: Isolement et caract\u00e9risation des principes actifs d\u2019abies balsamea et de cornus canadensis Vendredi 19 d\u00e9cembre 2014\u00a0 \u25aa\u00a0 9\u00a0h Local P1-4280 Direction de recherche Andr\u00e9 Pichette (UQAC) Codirection [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/\" \/>\r\n<meta property=\"og:site_name\" content=\"UQACtualit\u00e9s\" \/>\r\n<meta property=\"article:published_time\" content=\"2014-12-12T15:27:15+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"620\" \/>\r\n\t<meta property=\"og:image:height\" content=\"300\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Service des communications et des relations publiques\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service des communications et des relations publiques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/\",\"name\":\"Soutenance de th\u00e8se de Serge Lavoie - UQACtualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg\",\"datePublished\":\"2014-12-12T15:27:15+00:00\",\"dateModified\":\"2014-12-12T15:27:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#primaryimage\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg\",\"contentUrl\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg\",\"width\":620,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uqac.ca\/uqactualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soutenance de th\u00e8se de Serge Lavoie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#website\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/\",\"name\":\"UQACtualit\u00e9s\",\"description\":\"Le portail des nouvelles de l&#039;UQAC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uqac.ca\/uqactualites\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018\",\"name\":\"Service des communications et des relations publiques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g\",\"caption\":\"Service des communications et des relations publiques\"},\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/author\/bap\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soutenance de th\u00e8se de Serge Lavoie - UQACtualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/","og_locale":"fr_CA","og_type":"article","og_title":"Soutenance de th\u00e8se de Serge Lavoie - UQACtualit\u00e9s","og_description":"\u00c9tienne H\u00e9bert, doyen des \u00e9tudes de l\u2019UQAC, invite la communaut\u00e9 universitaire \u00e0 assister \u00e0 la soutenance de th\u00e8se de Serge Lavoie, \u00e9tudiant au doctorat en sciences de l\u2019environnement\u00a0: Isolement et caract\u00e9risation des principes actifs d\u2019abies balsamea et de cornus canadensis Vendredi 19 d\u00e9cembre 2014\u00a0 \u25aa\u00a0 9\u00a0h Local P1-4280 Direction de recherche Andr\u00e9 Pichette (UQAC) Codirection [&hellip;]","og_url":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/","og_site_name":"UQACtualit\u00e9s","article_published_time":"2014-12-12T15:27:15+00:00","og_image":[{"width":620,"height":300,"url":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg","type":"image\/jpeg"}],"author":"Service des communications et des relations publiques","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service des communications et des relations publiques","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/","url":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/","name":"Soutenance de th\u00e8se de Serge Lavoie - UQACtualit\u00e9s","isPartOf":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#primaryimage"},"image":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg","datePublished":"2014-12-12T15:27:15+00:00","dateModified":"2014-12-12T15:27:15+00:00","author":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018"},"breadcrumb":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#primaryimage","url":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg","contentUrl":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2012\/05\/avis-laCommunaut-.jpg","width":620,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.uqac.ca\/uqactualites\/2014\/12\/12\/soutenance-de-these-de-serge-lavoie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uqac.ca\/uqactualites\/"},{"@type":"ListItem","position":2,"name":"Soutenance de th\u00e8se de Serge Lavoie"}]},{"@type":"WebSite","@id":"https:\/\/www.uqac.ca\/uqactualites\/#website","url":"https:\/\/www.uqac.ca\/uqactualites\/","name":"UQACtualit\u00e9s","description":"Le portail des nouvelles de l&#039;UQAC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uqac.ca\/uqactualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018","name":"Service des communications et des relations publiques","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g","caption":"Service des communications et des relations publiques"},"url":"https:\/\/www.uqac.ca\/uqactualites\/author\/bap\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts\/28979"}],"collection":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/comments?post=28979"}],"version-history":[{"count":0,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts\/28979\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/media\/20989"}],"wp:attachment":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/media?parent=28979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/categories?post=28979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/tags?post=28979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}