{"id":46593,"date":"2024-03-28T08:50:33","date_gmt":"2024-03-28T12:50:33","guid":{"rendered":"https:\/\/www.uqac.ca\/uqactualites\/?p=46593"},"modified":"2024-07-24T13:52:14","modified_gmt":"2024-07-24T17:52:14","slug":"la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete","status":"publish","type":"post","link":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/","title":{"rendered":"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9"},"content":{"rendered":"\r\n<p><a href=\"https:\/\/chairesantedurable.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/chairesantedurable.ca\/\">La Chaire de recherche en sant\u00e9 durable <\/a>propose sa toute premi\u00e8re \u00e9cole d&rsquo;\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini du 28 mai au 1er juin prochain. Cette \u00e9cole d\u2019\u00e9t\u00e9, ouverte aux \u00e9tudiantes et \u00e9tudiants du 2e et 3e cycle ainsi qu\u2019aux postdoctorantes et postdoctorants de toutes les disciplines, souhaite favoriser un dialogue constructif avec les citoyennes, les citoyens, et les actrices et les acteurs locaux. En partenariat avec plusieurs acteurs mobilis\u00e9s du territoire, cette formation proposera des formules p\u00e9dagogiques innovantes et explorera des approches novatrices pour r\u00e9pondre aux enjeux de sant\u00e9 durable.<\/p>\r\n\r\n\r\n\r\n<p>Les personnes pr\u00e9sentes travailleront en \u00e9quipe intersectorielle selon une approche de r\u00e9solution par probl\u00e8me. Elles seront amen\u00e9es \u00e0 explorer un enjeu de leur choix parmi les cinq enjeux identifi\u00e9s par le milieu d\u2019accueil de l\u2019\u00e9cole d\u2019\u00e9t\u00e9\u00a0:<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\r\n<ul>\r\n<li>L\u2019adaptation aux changements climatiques;<\/li>\r\n\r\n\r\n\r\n<li>L\u2019accueil des nouveaux arrivants;<\/li>\r\n\r\n\r\n\r\n<li>Le collectif (le sens du bien commun, appartenance, le gain du travail d\u2019\u00e9quipe);<\/li>\r\n\r\n\r\n\r\n<li>La r\u00e9ussite \u00e9ducative;<\/li>\r\n\r\n\r\n\r\n<li>La pression sociale face au mode de vie (d\u00e9tresse psychologique des entrepreneurs et surconsommation).<\/li>\r\n<\/ul>\r\n<\/div><\/div>\r\n\r\n\r\n\r\n<p>L\u2019\u00c9cole d\u2019\u00e9t\u00e9 en sant\u00e9 durable est rendue possible gr\u00e2ce au soutien du <a href=\"https:\/\/frq.gouv.qc.ca\/sante\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fonds de recherche du Qu\u00e9bec \u2013 Sant\u00e9<\/a>.<\/p>\r\n\r\n\r\n\r\n<p>Pour en savoir plus ou pour vous inscrire, <a href=\"https:\/\/chairesantedurable.ca\/nouvelles\/ecole-dete-en-sante-durable-inscriptions-ouvertes\/\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/chairesantedurable.ca\/nouvelles\/ecole-dete-en-sante-durable-inscriptions-ouvertes\/\">visitez le site Web de la Chaire<\/a><\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\">\u00c0 propos de la Chaire en sant\u00e9 durable<\/h4>\r\n\r\n\r\n\r\n<p>Cr\u00e9\u00e9e en janvier 2023 par le Fonds de recherche du Qu\u00e9bec \u2013 Sant\u00e9 (FRQS), la Chaire est h\u00e9berg\u00e9e \u00e0 <a href=\"https:\/\/vitam.ulaval.ca\/\" target=\"_blank\" rel=\"noreferrer noopener\">VITAM<\/a> \u2013 Centre de recherche en sant\u00e9 durable du CIUSSS de la Capitale-Nationale affili\u00e9 \u00e0 l\u2019Universit\u00e9 Laval, et au<a href=\"https:\/\/cisd.uqac.ca\/\"> Centre intersectoriel en sant\u00e9 durable (CISD)<\/a> de l\u2019Universit\u00e9 du Qu\u00e9bec \u00e0 Chicoutimi. Elle est d\u00e9tenue par quatre co-titulaires : les citoyens Nadine Arbour et Guy Poulin ainsi que les deux professeurs Jean-Pierre Despr\u00e9s et <a href=\"https:\/\/www.uqac.ca\/portfolio\/catherinelaprise\/\" target=\"_blank\" rel=\"noreferrer noopener\">Catherine Laprise<\/a>. Le concept de sant\u00e9 durable se d\u00e9finit par un esprit sain dans un corps sain, dans un milieu de vie et un environnement sain, sur une plan\u00e8te en sant\u00e9. L\u2019objectif g\u00e9n\u00e9ral de la Chaire est de coordonner, stimuler et d\u00e9mocratiser la recherche intersectorielle en sant\u00e9 durable au Qu\u00e9bec.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>La Chaire de recherche en sant\u00e9 durable propose sa toute premi\u00e8re \u00e9cole d&rsquo;\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini du 28 mai au 1er juin prochain. Cette \u00e9cole d\u2019\u00e9t\u00e9, ouverte aux \u00e9tudiantes et \u00e9tudiants du 2e et 3e cycle ainsi qu\u2019aux postdoctorantes et postdoctorants de toutes les disciplines, souhaite favoriser un dialogue constructif [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":46597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2795,2,2854],"tags":[2850,19,2851],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9 - UQACtualit\u00e9s<\/title>\r\n<meta name=\"description\" content=\"La Chaire de recherche en sant\u00e9 durable propose sa toute premi\u00e8re \u00e9cole d&#039;\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/\" \/>\r\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9 - UQACtualit\u00e9s\" \/>\r\n<meta property=\"og:description\" content=\"La Chaire de recherche en sant\u00e9 durable propose sa toute premi\u00e8re \u00e9cole d&#039;\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/\" \/>\r\n<meta property=\"og:site_name\" content=\"UQACtualit\u00e9s\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-03-28T12:50:33+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-07-24T17:52:14+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"Service des communications et des relations publiques\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service des communications et des relations publiques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/\",\"name\":\"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9 - UQACtualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg\",\"datePublished\":\"2024-03-28T12:50:33+00:00\",\"dateModified\":\"2024-07-24T17:52:14+00:00\",\"author\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018\"},\"description\":\"La Chaire de recherche en sant\u00e9 durable propose sa toute premi\u00e8re \u00e9cole d'\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#primaryimage\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg\",\"contentUrl\":\"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Chaire de recherche en sant\u00e9 durable\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.uqac.ca\/uqactualites\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#website\",\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/\",\"name\":\"UQACtualit\u00e9s\",\"description\":\"Le portail des nouvelles de l&#039;UQAC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.uqac.ca\/uqactualites\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018\",\"name\":\"Service des communications et des relations publiques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g\",\"caption\":\"Service des communications et des relations publiques\"},\"url\":\"https:\/\/www.uqac.ca\/uqactualites\/author\/bap\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9 - UQACtualit\u00e9s","description":"La Chaire de recherche en sant\u00e9 durable propose sa toute premi\u00e8re \u00e9cole d'\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/","og_locale":"fr_CA","og_type":"article","og_title":"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9 - UQACtualit\u00e9s","og_description":"La Chaire de recherche en sant\u00e9 durable propose sa toute premi\u00e8re \u00e9cole d'\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini.","og_url":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/","og_site_name":"UQACtualit\u00e9s","article_published_time":"2024-03-28T12:50:33+00:00","article_modified_time":"2024-07-24T17:52:14+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg","type":"image\/jpeg"}],"author":"Service des communications et des relations publiques","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service des communications et des relations publiques","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/","url":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/","name":"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9 - UQACtualit\u00e9s","isPartOf":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#primaryimage"},"image":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#primaryimage"},"thumbnailUrl":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg","datePublished":"2024-03-28T12:50:33+00:00","dateModified":"2024-07-24T17:52:14+00:00","author":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018"},"description":"La Chaire de recherche en sant\u00e9 durable propose sa toute premi\u00e8re \u00e9cole d'\u00e9t\u00e9, qui se tiendra dans la ville de Dolbeau-Mistassini.","breadcrumb":{"@id":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#primaryimage","url":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg","contentUrl":"https:\/\/www.uqac.ca\/uqactualites\/wp-content\/uploads\/2024\/03\/NUM_EcoleEteSanteDurableH24_Uqctualite1920X1080.jpg","width":1920,"height":1080,"caption":"Chaire de recherche en sant\u00e9 durable"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uqac.ca\/uqactualites\/2024\/03\/28\/la-chaire-de-recherche-en-sante-durable-lance-sa-premiere-ecole-dete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uqac.ca\/uqactualites\/"},{"@type":"ListItem","position":2,"name":"La Chaire de recherche en sant\u00e9 durable lance sa premi\u00e8re \u00e9cole d\u2019\u00e9t\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.uqac.ca\/uqactualites\/#website","url":"https:\/\/www.uqac.ca\/uqactualites\/","name":"UQACtualit\u00e9s","description":"Le portail des nouvelles de l&#039;UQAC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uqac.ca\/uqactualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/366c45a0c4f0e677b41b4af5886e2018","name":"Service des communications et des relations publiques","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.uqac.ca\/uqactualites\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20fbbda8a292f59f2d3461a5b999c00b?s=96&d=mm&r=g","caption":"Service des communications et des relations publiques"},"url":"https:\/\/www.uqac.ca\/uqactualites\/author\/bap\/"}]}},"_links":{"self":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts\/46593"}],"collection":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/comments?post=46593"}],"version-history":[{"count":11,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts\/46593\/revisions"}],"predecessor-version":[{"id":48081,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/posts\/46593\/revisions\/48081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/media\/46597"}],"wp:attachment":[{"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/media?parent=46593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/categories?post=46593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uqac.ca\/uqactualites\/wp-json\/wp\/v2\/tags?post=46593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}